<br />
<b>Notice</b>:  Function _load_textdomain_just_in_time was called <strong>incorrectly</strong>. Translation loading for the <code>acf</code> domain was triggered too early. This is usually an indicator for some code in the plugin or theme running too early. Translations should be loaded at the <code>init</code> action or later. Please see <a href="https://developer.wordpress.org/advanced-administration/debug/debug-wordpress/">Debugging in WordPress</a> for more information. (This message was added in version 6.7.0.) in <b>/home/runcloud/webapps/ultimate-languages/wp-includes/functions.php</b> on line <b>6131</b><br />
<br />
<b>Notice</b>:  Function _load_textdomain_just_in_time was called <strong>incorrectly</strong>. Translation loading for the <code>insert-headers-and-footers</code> domain was triggered too early. This is usually an indicator for some code in the plugin or theme running too early. Translations should be loaded at the <code>init</code> action or later. Please see <a href="https://developer.wordpress.org/advanced-administration/debug/debug-wordpress/">Debugging in WordPress</a> for more information. (This message was added in version 6.7.0.) in <b>/home/runcloud/webapps/ultimate-languages/wp-includes/functions.php</b> on line <b>6131</b><br />
<br />
<b>Notice</b>:  Function _load_textdomain_just_in_time was called <strong>incorrectly</strong>. Translation loading for the <code>complianz-gdpr</code> domain was triggered too early. This is usually an indicator for some code in the plugin or theme running too early. Translations should be loaded at the <code>init</code> action or later. Please see <a href="https://developer.wordpress.org/advanced-administration/debug/debug-wordpress/">Debugging in WordPress</a> for more information. (This message was added in version 6.7.0.) in <b>/home/runcloud/webapps/ultimate-languages/wp-includes/functions.php</b> on line <b>6131</b><br />
<br />
<b>Notice</b>:  Function _load_textdomain_just_in_time was called <strong>incorrectly</strong>. Translation loading for the <code>wordpress-seo</code> domain was triggered too early. This is usually an indicator for some code in the plugin or theme running too early. Translations should be loaded at the <code>init</code> action or later. Please see <a href="https://developer.wordpress.org/advanced-administration/debug/debug-wordpress/">Debugging in WordPress</a> for more information. (This message was added in version 6.7.0.) in <b>/home/runcloud/webapps/ultimate-languages/wp-includes/functions.php</b> on line <b>6131</b><br />
{"id":5531,"date":"2018-10-16T16:39:33","date_gmt":"2018-10-16T15:39:33","guid":{"rendered":"https:\/\/ultimate-languages.smith.co.uk\/?p=5531"},"modified":"2023-11-13T11:10:43","modified_gmt":"2023-11-13T11:10:43","slug":"traduzioni-di-marketing-professionali","status":"publish","type":"post","link":"https:\/\/ultimate-languages.smith.co.uk\/it\/ultime-notizie\/traduzioni-di-marketing-professionali\/","title":{"rendered":"Traduzioni di marketing professionali"},"content":{"rendered":"<p>In passato tutto il materiale di marketing veniva stampato, tuttavia con l&#8217;espansione dell\u2019e-commerce e delle attivit\u00e0 online anche il marketing ha sentito l\u2019esigenza di passare a formati digitali quali banner web, newsletter, email marketing e, naturalmente, inserzioni pubblicitarie PPC (Pay-per-Click).<\/p>\n<p>Sebbene il web regni supremo, c\u2019\u00e8 ancora posto per la stampa tradizionale. Se la tua azienda partecipa a fiere ed esposizioni internazionali, dovrai sicuramente tradurre materiale promozionale cartaceo, come opuscoli, volantini, cartelloni, biglietti da visita e persino cataloghi.<\/p>\n<p>Indipendentemente dal tipo di risorsa utilizzata, vi sono aspetti importanti da tenere presente durante la localizzazione di contenuti marketing.<\/p>\n<h3><strong>1. Traduzione, transcreation o copywriting?<\/strong><\/h3>\n<p>I contenuti marketing sono solitamente testi pi\u00f9 creativi, pertanto \u00e8 importante prendere in considerazione il metodo di localizzazione pi\u00f9 adatto alla tua azienda e al contenuto scritto.<\/p>\n<p>Noi offriamo ai clienti tre opzioni, ognuna adatta per diversi tipi di contenuto. Prendiamole in esame\u2026<\/p>\n<h4>Traduzione<\/h4>\n<p>Molti ritengono che la traduzione consista semplicemente nella conversione di testo da una lingua ad un\u2019altra, parola per parola, tuttavia la realt\u00e0 non potrebbe essere pi\u00f9 diversa. Una buona traduzione \u00e8 di fatto una localizzazione, perch\u00e9 il linguista fa in modo che il contenuto della traduzione scorra in modo naturale nella lingua di arrivo, inserendo le sfumature, i riferimenti culturali e la terminologia locale.<\/p>\n<p>Questo metodo \u00e8 ideale per cataloghi, newsletter, biglietti da visita e potenzialmente brochure.<\/p>\n<h4>Transcreation<\/h4>\n<p>La transcreation va oltre, il linguista segue il testo sorgente, localizzandolo via via, ma dispone di maggiore libert\u00e0 nella struttura delle frasi e dei paragrafi. In linea con le istruzioni ricevute dal cliente, pu\u00f2 aggiungere informazioni e pu\u00f2 eliminare parti di testo se non sono pertinenti per il mercato di destinazione.<\/p>\n<p>Questo tipo di traduzione \u00e8 ideale per email marketing, banner web, volantini, cartelloni e opuscoli.<\/p>\n<h4>Copywriting<\/h4>\n<p>In base al livello di creativit\u00e0 del testo sorgente o al suo tipo di utilizzo futuro, potrebbe rivelarsi pi\u00f9 produttivo creare nuovi contenuti nella lingua di arrivo. In questi casi si ricorre a un copywriter professionale, che scrive direttamente nella propria lingua madre, si basa sulle istruzioni dettagliate, consulta il testo originale per trarre ispirazione e utilizza la guida di stile e i glossari dell\u2019azienda.<\/p>\n<p>Il copywriting \u00e8 ideale per messaggi email, banner, blog e inserzioni PPC che devono essere scritti in modo specifico per la clientela di arrivo.<\/p>\n<p>Ognuno di questi metodi richiede competenze e strumenti diversi. \u00c8 importante ricordare che i CAT e le memorie di traduzione sono utilizzabili solo per la traduzione. Nel caso della transcreation e del copywriting, il linguista dovr\u00e0 rielaborare tutto il testo e non potr\u00e0 quindi sfruttare i contenuti tradotti in precedenza. Ci\u00f2 comporta un aumento dei costi, ma allo stesso tempo testi localizzati in modo pi\u00f9 creativo. Prima di prendere una decisione, devi individuare cos\u2019\u00e8 pi\u00f9 importante per te e per il tuo business.<\/p>\n<p>Per maggiori informazioni sugli strumenti CAT,<a href=\"https:\/\/ultimatelanguages.com\/it\/2019\/06\/06\/cosa-sono-i-cat\/\"> leggi il nostro post sull\u2019argomento<\/a>.<\/p>\n<h3><strong>2. Formato dei file <\/strong><\/h3>\n<p>Poich\u00e9 i contenuti marketing di qualsiasi tipo sono solitamente ricchi di immagini, molte aziende affidano ad agenzie di design esterne il compito di creare e mantenere i propri contenuti creativi.<\/p>\n<p>Con l\u2019aumento della popolarit\u00e0 di Adobe Creative Cloud, la maggior parte delle agenzie utilizza Adobe InDesign, Adobe Photoshop, Adobe Illustrator e Adobe FrameMaker durante il processo di design. Esistono molte altre soluzioni di design, quali QuarkXPress, Coral Draw e Microsoft Publisher, ma il loro uso \u00e8 sempre meno frequente.<\/p>\n<p>\u00c8 importante ricordare che i fornitori di servizi di traduzione possono fare molto poco se ti limiti a inviare loro un file PDF. Se vuoi essere in grado di creare in modo veloce ed efficiente una versione localizzata della tua brochure aziendale, \u00e8 necessario tu invii all\u2019agenzia di traduzione i file sorgente originali ed editabili utilizzati da te o dall\u2019agenzia di design.<\/p>\n<p>Se invii un file PDF per la traduzione ti verr\u00e0 sicuramente chiesto di fornire i file originali, quindi assicurati di tenerli a portata di mano, inclusi caratteri speciali, immagini e link utilizzati durante il processo creativo.<\/p>\n<h3><strong>3. Immagini<\/strong><\/h3>\n<p>Come per i file PDF, i file di immagini statiche, come i JPEG non sono facilmente traducibili, pertanto \u00e8 necessario fornire anche i file sorgente originali per localizzare, per esempio, i tuoi banner per il web.<\/p>\n<p>In base alla nostra esperienza, i clienti spesso non riescono a trovare i file di immagini originali e \u2019unica opzione \u00e8 quella di ricreare l\u2019immagine nel modo migliore possibile. Questo comporta un numero di passaggi superiore, con conseguente aumento dei costi, dei tempi di conversione dei lead e una versione finale meno bella e con una risoluzione inferiore rispetto all\u2019originale. Rivolgendosi ad un\u2019agenzia di traduzioni occorre ricordarlo e chiedere informazioni sull\u2019approccio adottato per la localizzazione delle immagini.<\/p>\n<h3><strong>4. Desktop Publishing<\/strong><\/h3>\n<p>Una volta localizzati file e immagini, la fase successiva consiste nel sistemare testo e immagini e preparare il file per la stampa. Il servizio di desktop publishing (o composizione) garantisce che il testo tradotto sia incluso accuratamente nell\u2019impaginazione originale e che siano apportati eventuali aggiustamenti a livello di layout, caratteri, ecc. necessari per il testo di arrivo.<\/p>\n<p>La prima domanda da porsi \u00e8: chi si occuper\u00e0 di questa fase? Se il file originale \u00e8 stato creato da un\u2019agenzia di design esterna, \u00e8 probabile che tu voglia affidarle la gestione della fase di desktop publishing, ma \u00e8 bene assicurarsi che abbiano esperienza nel lavorare con altre lingue. In alternativa, molte agenzie di traduzione offrono ai propri clienti l&#8217;attivit\u00e0 di desktop publishing e forniscono materiale di marketing completamente localizzato, pronto per la distribuzione.<\/p>\n<h3><strong>5. Controlli visivi della qualit\u00e0 <\/strong><\/h3>\n<p>Dopo che i documenti sono stati sottoposti alla fase di composizione, prima di inoltrarli al cliente, \u00e8 opportuno eseguire un controllo visivo finale della qualit\u00e0. Questa operazione dovrebbe idealmente essere svolta dal traduttore originale, che eseguir\u00e0 un controllo linguistico e dell\u2019aspetto del testo per garantire che sia stato inserito correttamente e che lo stile e le dimensioni dei caratteri siano adeguati nella lingua di arrivo e allo stesso tempo individuer\u00e0 qualsiasi potenziale errore introdotto durante la fase di desktop publishing.<\/p>\n<p>In alternativa, potresti chiedere a un collega della tua sede locale di occuparsene, ma qualsiasi correzione suggerita dovr\u00e0 essere segnalata a chi si \u00e8 occupato della composizione, affinch\u00e9 applichi le modifiche e rispedisca i file aggiornati.<\/p>\n<p>Assicurati di verificare quali siano i costi aggiuntivi, molti fornitori di servizi di traduzione includono solo una fase di modifica nel costo della traduzione ed eventuali fasi aggiuntive sono addebitate con tariffa oraria.<\/p>\n<p>Una volta presi in considerazione tutti questi aspetti e definito il proprio approccio alle traduzioni di marketing, occorre delineare in modo dettagliato la propria strategia nella guida di stile, che verr\u00e0 utilizzata sia dai creatori dei contenuti interni, sia dai traduttori. Per maggiori informazioni sulla guida di stile, ti consigliamo la lettura del post <a href=\"https:\/\/ultimatelanguages.com\/it\/2019\/06\/06\/i-principi-fondamentali-della-traduzione\/\">sui principi fondamentali della traduzione.<\/a><\/p>\n<p>Noi di Ultimate Languages ci rendiamo conto che ogni progetto di marketing \u00e8 diverso e che per i clienti \u00e8 a volte difficile reperire i file sorgente originali, ma insieme troviamo sempre la soluzione pi\u00f9 adatta. Per parlare con un membro del nostro team delle tue esigenze di traduzione di materiale di marketing, contattaci <a href=\"https:\/\/ultimatelanguages.com\/it\/contattaci\/\">qui<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In passato tutto il materiale di marketing veniva stampato, tuttavia con l&#8217;espansione dell\u2019e-commerce e delle attivit\u00e0 online anche il marketing ha sentito l\u2019esigenza di passare a formati digitali quali banner web, newsletter, email marketing e, naturalmente, inserzioni pubblicitarie PPC (Pay-per-Click). Sebbene il web regni supremo, c\u2019\u00e8 ancora posto per la stampa tradizionale. Se la tua &hellip; <a href=\"https:\/\/ultimate-languages.smith.co.uk\/it\/ultime-notizie\/traduzioni-di-marketing-professionali\/\">Continued<\/a><\/p>\n","protected":false},"author":2,"featured_media":5278,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[161],"tags":[],"class_list":["post-5531","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultime-notizie"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Traduzioni di marketing professionali | Ultimate Languages<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Traduzioni di marketing professionali | Ultimate Languages\" \/>\n<meta property=\"og:description\" content=\"In passato tutto il materiale di marketing veniva stampato, tuttavia con l&#8217;espansione dell\u2019e-commerce e delle attivit\u00e0 online anche il marketing ha sentito l\u2019esigenza di passare a formati digitali quali banner web, newsletter, email marketing e, naturalmente, inserzioni pubblicitarie PPC (Pay-per-Click). Sebbene il web regni supremo, c\u2019\u00e8 ancora posto per la stampa tradizionale. Se la tua &hellip; Continued\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ultimate-languages.smith.co.uk\/it\/ultime-notizie\/traduzioni-di-marketing-professionali\/\" \/>\n<meta property=\"og:site_name\" content=\"Ultimate Languages\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/UltimateLSP\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-16T15:39:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-13T11:10:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ultimate-languages.smith.co.uk\/wp-content\/uploads\/2018\/10\/mastering_marketing_translation-gh1IgGFnhSk-unsplash.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1370\" \/>\n\t<meta property=\"og:image:height\" content=\"1137\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@UltimateLSP\" \/>\n<meta name=\"twitter:site\" content=\"@UltimateLSP\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ultimate-languages.smith.co.uk\/it\/ultime-notizie\/traduzioni-di-marketing-professionali\/\",\"url\":\"https:\/\/ultimate-languages.smith.co.uk\/it\/ultime-notizie\/traduzioni-di-marketing-professionali\/\",\"name\":\"Traduzioni di marketing professionali | Ultimate Languages\",\"isPartOf\":{\"@id\":\"https:\/\/ultimate-languages.smith.co.uk\/it\/#website\"},\"datePublished\":\"2018-10-16T15:39:33+00:00\",\"dateModified\":\"2023-11-13T11:10:43+00:00\",\"author\":{\"@id\":\"https:\/\/ultimate-languages.smith.co.uk\/it\/#\/schema\/person\/2d7d7a73a99a62236e5256ae131c16ee\"},\"breadcrumb\":{\"@id\":\"https:\/\/ultimate-languages.smith.co.uk\/it\/ultime-notizie\/traduzioni-di-marketing-professionali\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ultimate-languages.smith.co.uk\/it\/ultime-notizie\/traduzioni-di-marketing-professionali\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ultimate-languages.smith.co.uk\/it\/ultime-notizie\/traduzioni-di-marketing-professionali\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/ultimate-languages.smith.co.uk\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Traduzioni di marketing professionali\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ultimate-languages.smith.co.uk\/it\/#website\",\"url\":\"https:\/\/ultimate-languages.smith.co.uk\/it\/\",\"name\":\"Ultimate Languages\",\"description\":\"Words That Resonate\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ultimate-languages.smith.co.uk\/it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/ultimate-languages.smith.co.uk\/it\/#\/schema\/person\/2d7d7a73a99a62236e5256ae131c16ee\",\"name\":\"Ana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/ultimate-languages.smith.co.uk\/it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/ultimate-languages.smith.co.uk\/wp-content\/uploads\/2023\/11\/cropped-51289916310_4fb8ac58fa_c-1-96x96.jpg\",\"contentUrl\":\"https:\/\/ultimate-languages.smith.co.uk\/wp-content\/uploads\/2023\/11\/cropped-51289916310_4fb8ac58fa_c-1-96x96.jpg\",\"caption\":\"Ana\"},\"url\":\"https:\/\/ultimate-languages.smith.co.uk\/it\/author\/ultimate\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Traduzioni di marketing professionali | Ultimate Languages","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"it_IT","og_type":"article","og_title":"Traduzioni di marketing professionali | Ultimate Languages","og_description":"In passato tutto il materiale di marketing veniva stampato, tuttavia con l&#8217;espansione dell\u2019e-commerce e delle attivit\u00e0 online anche il marketing ha sentito l\u2019esigenza di passare a formati digitali quali banner web, newsletter, email marketing e, naturalmente, inserzioni pubblicitarie PPC (Pay-per-Click). Sebbene il web regni supremo, c\u2019\u00e8 ancora posto per la stampa tradizionale. Se la tua &hellip; Continued","og_url":"https:\/\/ultimate-languages.smith.co.uk\/it\/ultime-notizie\/traduzioni-di-marketing-professionali\/","og_site_name":"Ultimate Languages","article_publisher":"https:\/\/www.facebook.com\/UltimateLSP\/","article_published_time":"2018-10-16T15:39:33+00:00","article_modified_time":"2023-11-13T11:10:43+00:00","og_image":[{"width":1370,"height":1137,"url":"https:\/\/ultimate-languages.smith.co.uk\/wp-content\/uploads\/2018\/10\/mastering_marketing_translation-gh1IgGFnhSk-unsplash.jpg","type":"image\/jpeg"}],"author":"Ana","twitter_card":"summary_large_image","twitter_creator":"@UltimateLSP","twitter_site":"@UltimateLSP","twitter_misc":{"Scritto da":"Ana","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ultimate-languages.smith.co.uk\/it\/ultime-notizie\/traduzioni-di-marketing-professionali\/","url":"https:\/\/ultimate-languages.smith.co.uk\/it\/ultime-notizie\/traduzioni-di-marketing-professionali\/","name":"Traduzioni di marketing professionali | Ultimate Languages","isPartOf":{"@id":"https:\/\/ultimate-languages.smith.co.uk\/it\/#website"},"datePublished":"2018-10-16T15:39:33+00:00","dateModified":"2023-11-13T11:10:43+00:00","author":{"@id":"https:\/\/ultimate-languages.smith.co.uk\/it\/#\/schema\/person\/2d7d7a73a99a62236e5256ae131c16ee"},"breadcrumb":{"@id":"https:\/\/ultimate-languages.smith.co.uk\/it\/ultime-notizie\/traduzioni-di-marketing-professionali\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ultimate-languages.smith.co.uk\/it\/ultime-notizie\/traduzioni-di-marketing-professionali\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ultimate-languages.smith.co.uk\/it\/ultime-notizie\/traduzioni-di-marketing-professionali\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ultimate-languages.smith.co.uk\/it\/"},{"@type":"ListItem","position":2,"name":"Traduzioni di marketing professionali"}]},{"@type":"WebSite","@id":"https:\/\/ultimate-languages.smith.co.uk\/it\/#website","url":"https:\/\/ultimate-languages.smith.co.uk\/it\/","name":"Ultimate Languages","description":"Words That Resonate","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ultimate-languages.smith.co.uk\/it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/ultimate-languages.smith.co.uk\/it\/#\/schema\/person\/2d7d7a73a99a62236e5256ae131c16ee","name":"Ana","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/ultimate-languages.smith.co.uk\/it\/#\/schema\/person\/image\/","url":"https:\/\/ultimate-languages.smith.co.uk\/wp-content\/uploads\/2023\/11\/cropped-51289916310_4fb8ac58fa_c-1-96x96.jpg","contentUrl":"https:\/\/ultimate-languages.smith.co.uk\/wp-content\/uploads\/2023\/11\/cropped-51289916310_4fb8ac58fa_c-1-96x96.jpg","caption":"Ana"},"url":"https:\/\/ultimate-languages.smith.co.uk\/it\/author\/ultimate\/"}]}},"_links":{"self":[{"href":"https:\/\/ultimate-languages.smith.co.uk\/it\/wp-json\/wp\/v2\/posts\/5531","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ultimate-languages.smith.co.uk\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ultimate-languages.smith.co.uk\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ultimate-languages.smith.co.uk\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ultimate-languages.smith.co.uk\/it\/wp-json\/wp\/v2\/comments?post=5531"}],"version-history":[{"count":0,"href":"https:\/\/ultimate-languages.smith.co.uk\/it\/wp-json\/wp\/v2\/posts\/5531\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ultimate-languages.smith.co.uk\/it\/wp-json\/wp\/v2\/media\/5278"}],"wp:attachment":[{"href":"https:\/\/ultimate-languages.smith.co.uk\/it\/wp-json\/wp\/v2\/media?parent=5531"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ultimate-languages.smith.co.uk\/it\/wp-json\/wp\/v2\/categories?post=5531"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ultimate-languages.smith.co.uk\/it\/wp-json\/wp\/v2\/tags?post=5531"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}